{"id":136253,"date":"2023-02-13T15:04:47","date_gmt":"2023-02-13T14:04:47","guid":{"rendered":"http:\/\/bedrocan.com\/?p=136253"},"modified":"2025-06-19T14:35:53","modified_gmt":"2025-06-19T12:35:53","slug":"warum-gehen-niederlaendische-patienten-zum-coffeeshop","status":"publish","type":"post","link":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/","title":{"rendered":"Warum gehen niederl\u00e4ndische Patienten zum Coffeeshop?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1676296609602{margin-bottom: 0px !important;}&#8221;]Es gibt sogar Patienten, die auf ihren eigenen Dachb\u00f6den selbst Cannabis anbauen. Dies sind nur zwei Beispiele, wie sich niederl\u00e4ndische Patienten ihr Cannabis f\u00fcr die medizinische Anwendung beschaffen. Laut Angaben des <a href=\"https:\/\/www.trimbos.nl\/\" target=\"_blank\" rel=\"noopener\">Trimbos-Instituts<\/a> verwenden mehr als 130.000 Menschen in den Niederlanden Cannabis f\u00fcr medizinische Zwecke. Davon bekommen weniger als 7000 Patienten Cannabis vom Arzt verschrieben. Die meisten Patienten beziehen ihr Cannabis also von anderen Quellen, wie vom Coffeeshop oder aus eigenem Anbau.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1676296677130{margin-bottom: 0px !important;}&#8221;]\n<p class=\"NormalText\"><span lang=\"DE\">Das Trimbos-Institut f\u00fchrt eine unabh\u00e4ngige Umfrage unter Cannabis-Benutzern durch, um herauszufinden, wie der Zugriff auf und die Verf\u00fcgbarkeit von <a href=\"https:\/\/bedrocan.com\/de\/medizinische-fachkreise\/cannabis-als-medizin\/\" target=\"_blank\" rel=\"noopener\">medizinischem Cannabis<\/a> verbessert werden kann. <span class=\"NormalTextChar\">Die Umfrage ist inzwischen online. <\/span>Mit dieser Studie analysiert das Forschungs- und Wissensinstitut f\u00fcr psychische Gesundheit und Drogenkonsum die Bed\u00fcrfnisse und W\u00fcnsche von Patienten. Finanziert wird diese Studie von Bedrocan.<\/span><\/p>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1676295977431{margin-bottom: 0px !important;}&#8221;]\n<h3>Stimme der Patienten<\/h3>\n<p class=\"NormalText\"><span lang=\"DE\">Laut der Trimbos-Forscherin und Projektleiterin Lisa Strada ist es allgemein bekannt, dass Patienten Hanf, Haschisch, Hanf\u00f6l und andere Cannabisprodukte verwenden, um k\u00f6rperliche oder psychische Beschwerden zu lindern. Strada: \u201eAktuellere Erkenntnisse zeigen, dass fast eine halbe Million Menschen Produkte auf Cannabis-Basis f\u00fcr medizinische Anwendungen benutzen. Von diesen Menschen verwenden 50 % CBD-Produkte, unter anderem die in Drogerien erh\u00e4ltlichen CBD-Produkte.&#8221;Strada weiter: ,,Mit dieser Studie m\u00f6chten wir diesen Patienten eine Stimme geben. Patientenoriertierte F\u00fcrsorge bedeutet, dass die Bed\u00fcrfnisse des Patienten bei Entscheidungen im Pflegebereich leitend sind. W\u00e4hrend dies in anderen Bereichen des Gesundheitswesens die Norm ist, hinkt die medizinische Cannabisbehandlung in dieser Hinsicht hinterher.&#8221;<\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;160671&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1676295786400{margin-bottom: 0px !important;}&#8221;]\n<p class=\"NormalText\"><span lang=\"DE\">Seit 2003 k\u00f6nnen Patienten in den Niederlanden auf Vorlage eines \u00e4rztlichen Rezepts Cannabis bei der Apotheke bekommen. Mikael Kowal, Chief Scientific Officer von Bedrocan: \u201eTrotz der Tatsache, dass medizinisches Cannabis bereits seit zwanzig Jahren in den Niederlanden verf\u00fcgbar ist, beschaffen sich die meisten Menschen ihre Produkte nicht in der Apotheke. Es ist wichtig zu wissen, aus welchem Grund so viele Menschen die inoffiziellen Quellen bevorzugen. Auf welche Hindernisse sto\u00dfen sie? Ist der Preis f\u00fcr Cannabis in der Apotheke h\u00f6her, verweigern \u00c4rzte es zu verschreiben oder fehlen spezielle Produkte? Das ist unklar. Wir wissen es im Moment einfach nicht.\u201c<\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1676295819402{margin-bottom: 0px !important;}&#8221;]\n<p class=\"NormalText\"><span lang=\"DE\">Kowal erhofft sich f\u00fcr die Zukunft eine Ver\u00e4nderung: \u201eWir werden Strategien entwickeln m\u00fcssen, mit denen wir den Bed\u00fcrfnissen der Patienten, die aktuell Cannabis aus inoffiziellen Quellen beziehen, entsprechen k\u00f6nnen. Wir m\u00fcssen danach streben, dass mehr Patienten das standardisierte, kontrollierte und sichere Cannabis verwenden, anstatt Produkte ungepr\u00fcfter Qualit\u00e4t.&#8221;<\/span><\/p>\n[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1676296098785{margin-bottom: 0px !important;}&#8221;]\n<h3>Medusa-Studie<\/h3>\n<p>Der erste Teil der Medusa-Studie ist die Online-Umfrage. Die Beantwortung der Fragen beansprucht 10 bis 15 Minuten und unter allen Teilnehmern wird ein Gewinnpreis von 200,- Euro verlost. Es werden u.a. folgende Fragen gestellt:<\/p>\n<ul>\n<li>Gegen welche Beschwerden verwenden Sie Cannabis?<\/li>\n<li>Welche Cannabisprodukte verwenden Sie?<\/li>\n<li>Wie gut ist die Wirkung von Cannabis auf Ihre Beschwerden?<\/li>\n<li>Weshalb verwenden Sie kein \u00e4rztlich verschriebenes Cannabis?<\/li>\n<\/ul>\n<p>Nach der Umfrage k\u00f6nnen Teilnehmer an Folgebefragungen teilnehmen. Dabei handelt es sich einerseits um ein Online-Interview und andererseits um die M\u00f6glichkeit, uns eine kleine Probe ihres Cannabis zuzusenden. Wof\u00fcr sie sich entscheiden, bleibt den Teilnehmern \u00fcberlassen. Die Teilnahme ist freiwillig. Die Teilnehmer erhalten ein Entgelt in H\u00f6he von 40,- Euro je Folgebefragung.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][mk_padding_divider][vc_cta h2=&#8221;Teilnehmen&#8221; txt_align=&#8221;center&#8221; add_button=&#8221;bottom&#8221; btn_title=&#8221;Fragebogen&#8221; btn_align=&#8221;center&#8221;]Verwenden Sie Cannabis als Medikament? \u00a0Oder kennen Sie jemanden, der Cannabis als Medikament verwendet?[\/vc_cta][mk_padding_divider][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1676296859332{padding-right: 15px !important;padding-left: 15px !important;background-color: #f5f5f5 !important;border-radius: 5px !important;}&#8221;][vc_column][mk_padding_divider][vc_column_text css=&#8221;.vc_custom_1676296019054{margin-bottom: 0px !important;}&#8221;]\n<h3 style=\"text-align: center;\">Niederl\u00e4ndisches medizinisches Cannabissystem<\/h3>\n<p>In den Niederlanden ist die Vergabe von medizinischem Cannabis strikt getrennt von dem geduldeten Verkauf von Cannabis in Coffeeshops. Bereits seit 20 Jahren gibt es in den Niederlanden das Cannabisprogramm, wobei die niederl\u00e4ndische Regierung f\u00fcr die Produktion und den Vertrieb von Cannabis zust\u00e4ndig ist. Bedrocan wird von der Regierung beauftragt, dieses Cannabis nach strengen Richtlinien anzubauen. Dieses Cannabis ist nur auf \u00e4rztliches Rezept erh\u00e4ltlich. Dar\u00fcber hinaus sind zahlreiche CBD-haltige Produkte in Drogerien und im Internet frei verk\u00e4uflich. CBD ist ein nicht psychoaktiver Bestandteil von Cannabis, der nicht unter das niederl\u00e4ndische Bet\u00e4ubungsmittelgesetz f\u00e4llt.[\/vc_column_text][mk_padding_divider][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1676296609602{margin-bottom: 0px !important;}&#8221;]Es gibt sogar Patienten, die auf ihren eigenen Dachb\u00f6den selbst Cannabis anbauen. Dies sind nur zwei Beispiele, wie sich niederl\u00e4ndische Patienten ihr Cannabis f\u00fcr die medizinische Anwendung beschaffen. Laut Angaben des Trimbos-Instituts verwenden mehr als 130.000 Menschen in den Niederlanden Cannabis f\u00fcr medizinische Zwecke. Davon bekommen weniger als 7000 Patienten Cannabis vom [&hellip;]<\/p>\n","protected":false},"author":2019,"featured_media":151290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[140],"tags":[],"class_list":["post-136253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coffeeshop: warum Patienten sich hierf\u00fcr entscheiden?<\/title>\n<meta name=\"description\" content=\"Eine Studie untersucht, warum niederl\u00e4ndische Patienten lieber zum Coffeeshop gehen, als ihren Arzt zu besuchen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coffeeshop: warum Patienten sich hierf\u00fcr entscheiden?\" \/>\n<meta property=\"og:description\" content=\"Eine Studie untersucht, warum niederl\u00e4ndische Patienten lieber zum Coffeeshop gehen, als ihren Arzt zu besuchen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/\" \/>\n<meta property=\"og:site_name\" content=\"Bedrocan - standardised medicinal cannabis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bedrocan\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-13T14:04:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T12:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bedrocan.com\/wp-content\/uploads\/personeel-kantine-emmeloord-bedrocan-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Elsas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Elsas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/\"},\"author\":{\"name\":\"Mariana Elsas\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/person\\\/fbfca05cbf173877e83387331c590c69\"},\"headline\":\"Warum gehen niederl\u00e4ndische Patienten zum Coffeeshop?\",\"datePublished\":\"2023-02-13T14:04:47+00:00\",\"dateModified\":\"2025-06-19T12:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/\"},\"wordCount\":832,\"publisher\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/personeel-kantine-emmeloord-bedrocan-2.jpg\",\"articleSection\":[\"Archive\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/\",\"name\":\"Coffeeshop: warum Patienten sich hierf\u00fcr entscheiden?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/personeel-kantine-emmeloord-bedrocan-2.jpg\",\"datePublished\":\"2023-02-13T14:04:47+00:00\",\"dateModified\":\"2025-06-19T12:35:53+00:00\",\"description\":\"Eine Studie untersucht, warum niederl\u00e4ndische Patienten lieber zum Coffeeshop gehen, als ihren Arzt zu besuchen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/personeel-kantine-emmeloord-bedrocan-2.jpg\",\"contentUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/personeel-kantine-emmeloord-bedrocan-2.jpg\",\"width\":1024,\"height\":682,\"caption\":\"Coffeeshop\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum gehen niederl\u00e4ndische Patienten zum Coffeeshop?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/\",\"name\":\"Bedrocan\",\"description\":\"medicinal cannabis\",\"publisher\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#organization\",\"name\":\"Bedrocan\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/logo-bedrocan-mail.png\",\"contentUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/logo-bedrocan-mail.png\",\"width\":185,\"height\":31,\"caption\":\"Bedrocan\"},\"image\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Bedrocan\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bedrocan\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bedrocan_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/person\\\/fbfca05cbf173877e83387331c590c69\",\"name\":\"Mariana Elsas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891eb276b6a36cf4e22c5fcc9e739c8656b6f91e190e6efa45ad1c252ab6dbad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891eb276b6a36cf4e22c5fcc9e739c8656b6f91e190e6efa45ad1c252ab6dbad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/891eb276b6a36cf4e22c5fcc9e739c8656b6f91e190e6efa45ad1c252ab6dbad?s=96&d=mm&r=g\",\"caption\":\"Mariana Elsas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coffeeshop: warum Patienten sich hierf\u00fcr entscheiden?","description":"Eine Studie untersucht, warum niederl\u00e4ndische Patienten lieber zum Coffeeshop gehen, als ihren Arzt zu besuchen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/","og_locale":"de_DE","og_type":"article","og_title":"Coffeeshop: warum Patienten sich hierf\u00fcr entscheiden?","og_description":"Eine Studie untersucht, warum niederl\u00e4ndische Patienten lieber zum Coffeeshop gehen, als ihren Arzt zu besuchen.","og_url":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/","og_site_name":"Bedrocan - standardised medicinal cannabis","article_publisher":"https:\/\/www.facebook.com\/Bedrocan","article_published_time":"2023-02-13T14:04:47+00:00","article_modified_time":"2025-06-19T12:35:53+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/bedrocan.com\/wp-content\/uploads\/personeel-kantine-emmeloord-bedrocan-2.jpg","type":"image\/jpeg"}],"author":"Mariana Elsas","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mariana Elsas","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#article","isPartOf":{"@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/"},"author":{"name":"Mariana Elsas","@id":"https:\/\/bedrocan.com\/de\/#\/schema\/person\/fbfca05cbf173877e83387331c590c69"},"headline":"Warum gehen niederl\u00e4ndische Patienten zum Coffeeshop?","datePublished":"2023-02-13T14:04:47+00:00","dateModified":"2025-06-19T12:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/"},"wordCount":832,"publisher":{"@id":"https:\/\/bedrocan.com\/de\/#organization"},"image":{"@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#primaryimage"},"thumbnailUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/personeel-kantine-emmeloord-bedrocan-2.jpg","articleSection":["Archive"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/","url":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/","name":"Coffeeshop: warum Patienten sich hierf\u00fcr entscheiden?","isPartOf":{"@id":"https:\/\/bedrocan.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#primaryimage"},"image":{"@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#primaryimage"},"thumbnailUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/personeel-kantine-emmeloord-bedrocan-2.jpg","datePublished":"2023-02-13T14:04:47+00:00","dateModified":"2025-06-19T12:35:53+00:00","description":"Eine Studie untersucht, warum niederl\u00e4ndische Patienten lieber zum Coffeeshop gehen, als ihren Arzt zu besuchen.","breadcrumb":{"@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#primaryimage","url":"https:\/\/bedrocan.com\/wp-content\/uploads\/personeel-kantine-emmeloord-bedrocan-2.jpg","contentUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/personeel-kantine-emmeloord-bedrocan-2.jpg","width":1024,"height":682,"caption":"Coffeeshop"},{"@type":"BreadcrumbList","@id":"https:\/\/bedrocan.com\/de\/warum-gehen-niederlaendische-patienten-zum-coffeeshop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bedrocan.com\/de\/"},{"@type":"ListItem","position":2,"name":"Warum gehen niederl\u00e4ndische Patienten zum Coffeeshop?"}]},{"@type":"WebSite","@id":"https:\/\/bedrocan.com\/de\/#website","url":"https:\/\/bedrocan.com\/de\/","name":"Bedrocan","description":"medicinal cannabis","publisher":{"@id":"https:\/\/bedrocan.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bedrocan.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bedrocan.com\/de\/#organization","name":"Bedrocan","url":"https:\/\/bedrocan.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bedrocan.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/bedrocan.com\/wp-content\/uploads\/logo-bedrocan-mail.png","contentUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/logo-bedrocan-mail.png","width":185,"height":31,"caption":"Bedrocan"},"image":{"@id":"https:\/\/bedrocan.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bedrocan","https:\/\/www.linkedin.com\/company\/bedrocan\/","https:\/\/www.instagram.com\/bedrocan_international\/"]},{"@type":"Person","@id":"https:\/\/bedrocan.com\/de\/#\/schema\/person\/fbfca05cbf173877e83387331c590c69","name":"Mariana Elsas","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/891eb276b6a36cf4e22c5fcc9e739c8656b6f91e190e6efa45ad1c252ab6dbad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/891eb276b6a36cf4e22c5fcc9e739c8656b6f91e190e6efa45ad1c252ab6dbad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/891eb276b6a36cf4e22c5fcc9e739c8656b6f91e190e6efa45ad1c252ab6dbad?s=96&d=mm&r=g","caption":"Mariana Elsas"}}]}},"_links":{"self":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts\/136253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/users\/2019"}],"replies":[{"embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/comments?post=136253"}],"version-history":[{"count":5,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts\/136253\/revisions"}],"predecessor-version":[{"id":203673,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts\/136253\/revisions\/203673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/media\/151290"}],"wp:attachment":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/media?parent=136253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/categories?post=136253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/tags?post=136253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}