{"id":34562,"date":"2020-05-06T11:39:19","date_gmt":"2020-05-06T09:39:19","guid":{"rendered":"http:\/\/bedrocan.com\/the-current-state-of-medical-cannabis-investing\/"},"modified":"2026-06-22T17:10:46","modified_gmt":"2026-06-22T15:10:46","slug":"aktueller-stand-medizinischer-cannabis-investitionen","status":"publish","type":"post","link":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/","title":{"rendered":"Aktueller Stand medizinischer Cannabis-Investitionen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1590404292136{margin-bottom: 0px !important;}&#8221;]In den vergangenen Jahren gab es einen enormen Hype um die internationale Cannabisbranche. Dieser Hype, der haupts\u00e4chlich auf den boomenden kanadischen Cannabis Markt zur\u00fcckzuf\u00fchren ist, hat insbesondere bei Investoren in diesem Sektor unrealistische Erwartungen geweckt.\u00a0Angesichts der Tatsache, dass immer mehr Cannabis-Unternehmen nicht in der Lage sind, diesen \u00fcberh\u00f6hten Anspr\u00fcchen gerecht zu werden, hat die Branche nun einen entscheidenden Moment des \u00dcbergangs erreicht, der durch die COVID-19-Krise nur noch beschleunigt wird. Auf welche Herausforderungen st\u00f6\u00dft Bedrocan als Branchenexperte im Hinblick auf Investments in der medizinischen Cannabisbranche? Mit welchen regulatorischen Herausforderungen sehen wir uns als Auftragsproduzent von medizinischem Cannabis im Auftrag der niederl\u00e4ndischen Regierung konfrontiert? Wir m\u00f6chten Ihnen als potenzielle Investoren in diesem Artikel einige wichtige Informationen vermitteln.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1590403361158{margin-bottom: 0px !important;}&#8221;]<em>Autor: Andrew Kraszewski (Business Development, Bedrocan)<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_padding_divider][vc_single_image image=&#8221;34226&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1749549472678{margin-bottom: 0px !important;}&#8221;]\n<h2><strong>Kapitalmarktaktivit\u00e4ten in Nordamerika<\/strong><\/h2>\n<p>Cannabis sowohl als Arzneimittel als auch als Konsumgut hat in letzter Zeit, vor allem aufgrund der Kapitalmarktaktivit\u00e4ten in Nordamerika, gro\u00dfe Aufmerksamkeit erregt.<\/p>\n<p>Im Vorfeld der Legalisierung von rekreativen Cannabis in Kanada im Oktober 2018 wurden Milliarden kanadischer Dollar in den Sektor gelenkt, was eine neue \u00c4ra des &#8220;gr\u00fcnen Ansturms&#8221; und des Aufschwungs der legalen Cannabism\u00e4rkte einleitete.<\/p>\n<p>Doch nun, im zweiten Jahr der umfassenden Legalisierung von Cannabis in Kanada, zeichnen die Cannabism\u00e4rkte ein weitaus d\u00fcsteres Bild, da einem Teil der bekanntesten kanadischen Herstellernamen f\u00fcr Cannabis das Geld ausgeht.<\/p>\n<p>Angesichts der jetzt zu erwartenden bedeutenden Ver\u00e4nderungen in der Branche hat die Frage, wie wir \u00fcberhaupt dorthin gelangen konnten und was dies f\u00fcr den sich weiterentwickelnden Sektor bedeutet, erhebliche Bedeutung f\u00fcr Bedrocan und unseren Platz im internationalen Kontext.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][mk_padding_divider][vc_single_image image=&#8221;34234&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/business.financialpost.com\/cannabis\/how-a-handful-of-hedge-funds-cornered-cannabis-financing-and-made-a-killing-in-the-process&#8221;][mk_padding_divider][\/vc_column][vc_column width=&#8221;1\/2&#8243;][mk_padding_divider][mk_padding_divider][vc_column_text css=&#8221;.vc_custom_1590404347044{margin-bottom: 0px !important;}&#8221;]Der Beginn meiner pers\u00f6nlichen Reise im Bereich des medizinischen Cannabis nahm im Januar 2016 in Nordamerika seinen Anfang. Zum damaligen Zeitpunkt waren weder Gro\u00dfbanken noch gro\u00dfe institutionelle Investoren in der Branche aktiv, da es sich beim Cannabis um eine kontrollierte Substanz handelte und auch heute noch handelt, sodass jegliche kommerzielle Bet\u00e4tigung mit Cannabis ein hohes Ma\u00df an regulativen Risiken birgt.<\/p>\n<p>Indessen waren in Kanada, wo die Liberalisierung des heimischen Cannabismarktes im Gange war (sowie in zahlreichen Bundesstaaten der USA, wo einzelstaatliche Gesetze f\u00fcr medizinische Cannabis-Programme und heimische Cannabis-Programme eingef\u00fchrt wurden), einige Geldgeber und Investmentbanken bereit, die notwendigen Risiken einzugehen, um diesen aufbl\u00fchenden Sektor zu unterst\u00fctzen und zu finanzieren.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1699436866502{margin-bottom: 0px !important;}&#8221;]\n<h2>Cannabis-Investitionen in Kanada<\/h2>\n<p>Mark Rendells <a href=\"https:\/\/financialpost.com\/cannabis\/how-a-handful-of-hedge-funds-cornered-cannabis-financing-and-made-a-killing-in-the-process\" target=\"_blank\" rel=\"noopener noreferrer\">Expos\u00e9<\/a> (Financial Post 2018) \u00fcber die Finanzierung des kanadischen Cannabismarktes enth\u00fcllte, dass interessanterweise nur eine Handvoll Unternehmen f\u00fcr die Finanzierung gro\u00dfer Teile der Industrie verantwortlich waren. Die Finanziers waren opportunistische Hedge-fonds, die \u00fcblicherweise nicht die langfristigen Interessen der Unternehmen im Auge haben. Wie von Rendell hervorgehoben wird, wandten diese Investoren verschiedene Taktiken an, um kurzfristige, \u00fcbergro\u00dfe Renditen zu erzielen. Sie recycelten ihr Kapital von Gesch\u00e4ft zu Gesch\u00e4ft.<\/p>\n<p>Zu jener Zeit herrschte bei den gro\u00dfen kanadischen Firmen die weitverbreitete Meinung vor, dass man beabsichtigte, den heimischen Markt und die medizinischen Cannabism\u00e4rkte im Ausland zu beherrschen. Mit dem Ziel die Gr\u00f6\u00dften und Besten zu sein, ging es vor allem darum, Kapazit\u00e4ten aufzubauen.<\/p>\n<p>Kapazit\u00e4t als Ma\u00dfstab f\u00fcr Unternehmen war eine Ma\u00dfeinheit, auf die Investoren bei der Bewertung eines Cannabisunternehmens h\u00e4ufig verwiesen, und dies aus dem simplen Grund, dass das Ertragspotenzial eines Unternehmens mit zunehmender Produktionsfl\u00e4che zunahm.<\/p>\n<h2><strong>Kanadischer Dollar<\/strong><\/h2>\n<p>Infolgedessen steckten die Betreiber Millionen kanadischer Dollar in den Bau von Produktionsanlagen sowohl in Kanada als auch in L\u00e4ndern wie D\u00e4nemark, Jamaika und Kolumbien. Letztendlich spielte es keine Rolle, ob diese Investitionen strategisch sinnvoll waren oder nicht, denn die Investoren dieser Unternehmen, die opportunistischen Hedge-fonds, waren lediglich daran interessiert, einen Finanzhandel durchzuf\u00fchren, in der Regel mit einem Kleinanleger am \u00e4u\u00dfersten Ende der Kette, dem suggeriert wurde zu glauben, dass der Cannabis-Hype sich gelohnt habe.<\/p>\n<p>Angesichts der Tatsache, dass die kanadischen und internationalen Produktionsst\u00e4tten mittlerweile stillgelegt wurden, wird deutlich, dass viele Unternehmen ihre Anbaukapazit\u00e4ten \u00fcberdimensionierten.<\/p>\n<p>In Kanada entwickelt sich auf dem heimischen Markt eine immer gr\u00f6\u00dfer werdende Kluft zwischen dem Absatzvolumen angesichts der begrenzten Anzahl der bisher er\u00f6ffneten Einzelhandelsgesch\u00e4fte und der Menge an getrocknetem Cannabis, welches derzeit in den Vertriebskan\u00e4len vorr\u00e4tig ist. In dem jetzt eingetretenen Konkurrenzkampf zur Talsohle schwenken die kanadischen Anbieter auf den Freilandkulturanbau um, um zum einen die Anbaukosten zu senken und letztendlich Rentabilit\u00e4t zu erwirtschaften.<\/p>\n<p>Hinsichtlich des internationalen R\u00fcckzugs ist die Lage jedoch noch komplexer und erfordert ein umfassendes Verst\u00e4ndnis des regulatorischen Umfelds, in dem medizinische Cannabis-Unternehmen t\u00e4tig sind.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1749549532620{margin-bottom: 0px !important;}&#8221;]\n<h2><strong>Einheits\u00fcbereinkommen des Jahres 1961<\/strong><\/h2>\n<p>Das bedeutendste Gesetzeswerk, das sich weltweit auf die Herstellung von medizinischem Cannabis bezieht, ist das Einheits\u00fcbereinkommen der Vereinten Nationen zum Thema Bet\u00e4ubungsmittel aus dem Jahr 1961 (the<strong> \u201c<\/strong>Single Convention\u201d).<\/p>\n<p>Das internationale Bet\u00e4ubungsmittel-Kontrollgesetz schreibt vor, dass der Gebrauch von Cannabis auf rein wissenschaftliche und medizinische Zwecke beschr\u00e4nkt ist. Den L\u00e4ndern wird vorgeschrieben ein strenges Kontrollsystem f\u00fcr medizinisches Cannabis mittels einer Regierungsbeh\u00f6rde einzurichten.<\/p>\n<p>Letztendlich r\u00e4umt es den L\u00e4ndern jedoch eine gewisse Flexibilit\u00e4t bei der Auslegung dieser Kontrollmechanismen ein. Das Rahmenabkommen verlangt jedoch ausdr\u00fccklich, dass lokale Regierungsbeh\u00f6rden medizinisches Cannabis vor dem Verkauf im In- oder Ausland ankaufen und in direkten Besitz nehmen.<\/p>\n<h2><strong>Patienten Zugang<\/strong><\/h2>\n<p>Im Rahmen medizinischer Cannabisprogramme f\u00fcr den h\u00e4uslichen Gebrauch erhalten Patienten Zugang zu medizinischem Cannabis im Rahmen von Sonderzugangsregelungen (Special Access Schemes), f\u00fcr die jedoch der Nachweis erforderlich ist, dass Patienten ihre M\u00f6glichkeiten in Bezug auf die Erprobung registrierter Medikamente ausgesch\u00f6pft haben. Die Bereitstellung des Zugangs zu medizinischem Cannabis im Rahmen von Sonderzugangsprogrammen entspricht nat\u00fcrlich voll und ganz der Single Convention.<\/p>\n<p>Was die Umsetzung des Einheits\u00fcbereinkommens anbelangt wenden die einzelnen L\u00e4nder jedoch unterschiedlich strenge Ma\u00dfst\u00e4be an. Die Niederlande sind eines der L\u00e4nder mit der strengsten Auslegungen des Einheits\u00fcbereinkommens.<\/p>\n<p>In den Niederlanden ist das OMC (niederl\u00e4ndisches Amt f\u00fcr medizinisches Cannabis) mit der \u00dcberwachung der Cannabisproduktion f\u00fcr medizinische und wissenschaftliche Zwecke beauftragt. Das OMC vertreibt Bedrocan Cannabis als wirksamen pharmazeutischen Wirkstoff an Apotheken, Forscher und pharmazeutische Abnehmer im In- und Ausland. Bedrocan ist Auftragshersteller der niederl\u00e4ndischen Regierung.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1699436894861{margin-bottom: 0px !important;}&#8221;]\n<h2><strong>Kontrollierte Substanz<\/strong><\/h2>\n<p>Es ist mir wichtig, die Tatsache hervorzuheben, dass es sich bei medizinischem Cannabis um eine streng kontrollierte Substanz handelt, die nur schwer international gehandelt werden kann.<\/p>\n<p>Dar\u00fcber hinaus wird hervorgehoben, dass medizinisches Cannabis wie jedes andere pharmazeutische Produkt behandelt werden sollte, welches nach den Grunds\u00e4tzen der guten Herstellungspraxis (&#8220;GMP&#8221;) hergestellt werden muss.<\/p>\n<p>Zahlreiche Unternehmen entdeckten schlicht und einfach, dass der Export von medizinischem Cannabis aus einer Vielzahl von Gr\u00fcnden unm\u00f6glich sein w\u00fcrde, und sahen sich gezwungen, sich entweder auf inl\u00e4ndische Absatzm\u00f6glichkeit zu konzentrieren oder g\u00e4nzlich die Segel zu streichen.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;34262&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1749549557237{margin-bottom: 0px !important;}&#8221;]Kurz gesagt, Businesspl\u00e4ne, die auf dem Export von <a href=\"https:\/\/bedrocan.com\/de\/cannabis-produkte\/\">medizinischem Cannabis<\/a> von einer Jurisdiktion in eine andere basieren, haben bislang die in sie gesetzten Erwartungen nicht erf\u00fcllt, da die Herausforderungen untersch\u00e4tzt wurden, die das Einheits\u00fcbereinkommen mit sich bringt.<\/p>\n<p>Es zeigt sich, dass das Vorhandensein einer Lizenz zum Anbau, Verarbeitung und Export von medizinischem Cannabis nur dann von Bedeutung ist, wenn es einen Abnehmer in einem anderen Staat gibt &#8211; einem Staat, der bereits im Besitz einer g\u00fcltigen Importgenehmigung seiner zust\u00e4ndigen Beh\u00f6rde ist.<\/p>\n<h2><strong>Die Niederlande und ihre Position\u00a0<\/strong><\/h2>\n<p>Die Niederlande legalisierten bereits 2003 als erstes europ\u00e4isches Land medizinisches Cannabis und exportieren erstmals 2007 pharmazeutisches Cannabis nach Italien und Finnland.<\/p>\n<p>Wichtig zu betonen, ist jedoch, dass das niederl\u00e4ndische Amt f\u00fcr medizinisches Cannabis zwar schon seit l\u00e4ngerem Cannabis exportiert, dies jedoch nie das Prim\u00e4rziel des medizinischen Cannabis-Programms war; vielmehr stand der inl\u00e4ndische Patient immer im Mittelpunkt.<\/p>\n<p>Insofern sind die niederl\u00e4ndischen Exporte im Laufe der Zeit als eine Folge der weltweiten Nachfrage organisch gewachsen. So erhielt zum Beispiel die niederl\u00e4ndische Regierung 2019 einen formellen Antrag ihrer deutschen Kollegen, die j\u00e4hrliche Menge der nach Deutschland importierten medizinischen Cannabis-Bl\u00fcte von 1.500 kg auf 2.500 kg zu erh\u00f6hen. Ein Antrag, der im Jahr 2020 bewilligt wurde.<\/p>\n<h3><strong>Alleinzulieferer<\/strong><\/h3>\n<p>Bedrocan, dessen Anf\u00e4nge sich bis in die 1990er Jahre als Saatgutproduktionsunternehmen zur\u00fcckverfolgen lassen, ist seit 2003 der Alleinzulieferer des OMC und damit einer der \u00e4ltesten medizinischen Cannabishersteller Europas.<\/p>\n<p>Zweifellos hat uns die schiere L\u00e4nge unserer Unternehmensgeschichte nicht nur die M\u00f6glichkeit gegeben, unsere Aktivit\u00e4ten in einer kapitaleffizienten Weise zu erweitern, als der internationale medizinische Cannabismarkt expandierte, sondern auch unser Anbau-Know-how zu verfeinern.<\/p>\n<p>Die hochwertige Qualit\u00e4t der Produkte, die Bedrocan seit \u00fcber f\u00fcnfundzwanzig Jahren liefert, in Verbindung mit erprobten Anbautechniken f\u00fchrt dazu, dass wir in der Lage sind, qualitativ hochwertige und best\u00e4ndige Cannabisbl\u00fcten zu produzieren.<\/p>\n<p>Dar\u00fcber hinaus hat Bedrocan in den Bau von Anbaubetrieben investiert, die <a href=\"https:\/\/bedrocan.com\/de\/ueber-uns\/qualitaetsstandards\/\">GMP-zertifiziert<\/a> sind, was bedeutet, dass wir uns bem\u00fchen, den h\u00f6chstm\u00f6glichen Standard f\u00fcr unsere Produkte zu erreichen. Aus diesem Grund sind die Produkte von Bedrocan weltweit in klinischen Forschungsprojekten, Produktentwicklungsprojekten und Special Access Schemes zu finden.<\/p>\n<p>Aus unserer Sicht ist das Thema der Standardisierung heute eines der gr\u00f6\u00dften Hindernisse f\u00fcr die Akzeptanz und Verschreibung von medizinischem Cannabis. Es ist schlicht und einfach eine Herausforderung, medizinisches Cannabis zu verschreiben, wenn man die genauen Inhaltsstoffe und Mengen an Cannabinoiden in einem auf Cannabis basierenden Pr\u00e4parat nicht kennt.<\/p>\n<p>Dar\u00fcber hinaus ist ein standardisiertes und hochwertiges Rohmaterial als <a href=\"https:\/\/bedrocan.com\/de\/cannabis-produkte\/\">aktiver pharmazeutischer Inhaltsstoff<\/a> f\u00fcr jede pharmazeutische Produktentwicklung von entscheidender Bedeutung.<\/p>\n<p>Zweifelsfrei hat unsere Kompetenz, die Herstellung von Cannabisbl\u00fcten zu standardisieren, bei Aufsichtsbeh\u00f6rden, Forschern, \u00c4rzten und Patienten Vertrauen in die Produkte von Bedrocan geschaffen.<\/p>\n<h3><strong>Vertrauen<\/strong><\/h3>\n<p>Dieses Vertrauen, das in die medizinische Cannabisbl\u00fcte der Firma Bedrocan neben der strikten Einhaltung des Einheits\u00fcbereinkommens durch die niederl\u00e4ndische Regierung aufgebaut wurde, hat dazu gef\u00fchrt, dass die Niederlande zu den wenigen L\u00e4ndern geh\u00f6ren, die in der Lage sind, medizinisches Cannabis auf einer konsistenten Basis erfolgreich zu exportieren.<\/p>\n<p>Alles in allem ist es umso wahrscheinlicher, dass Importstaaten einem Vertragsunternehmen der Landesregierung vertrauen, welche innerhalb der Grenzen der Single Convention operiert. Des Weiteren ist f\u00fcr diese Staaten wichtig, medizinisches Cannabis zu importieren, welches im Rahmen der GMP angebaut und verarbeitet wurde &#8211; das heisst medizinisches Cannabis, das \u00fcber alle notwendigen Unterlagen verf\u00fcgt, dies zu belegen.<\/p>\n<p>Aufgrund dieser Faktoren haben die Niederlande zusammen mit Bedrocan eine einzigartige Position in der internationalen Lieferkette f\u00fcr medizinisches Cannabis eingenommen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;34248&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1699436956218{margin-bottom: 0px !important;}&#8221;]\n<h2><strong>Investitionen in den medizinischen Cannabis-Sektor<\/strong><\/h2>\n<p>F\u00fcr Investoren, die bereits in den medizinischen Cannabissektor investiert haben oder dies in Betracht ziehen, ist das Verst\u00e4ndnis der regulatorischen Gegebenheiten die wichtigste Voraussetzung um fundierte Investitionsentscheidungen treffen zu k\u00f6nnen.<\/p>\n<p>Die internationale medizinische Cannabisindustrie ist, offen gesagt, ein sehr schwieriges Gesch\u00e4ft, und der Aufbau von Lieferketten \u00fcber Grenzen hinweg ist mit regulatorischen Herausforderungen verbunden.<\/p>\n<p>Dar\u00fcber hinaus hat sich die Investitionslandschaft in den letzten zw\u00f6lf Monaten nach einem rapiden R\u00fcckgang der B\u00f6rsenbewertungen, der durch die COVID-19-Krise nur noch verst\u00e4rkt wurde, dramatisch ver\u00e4ndert. Es liegt auf der Hand, dass sich die Geschichte nicht selten wiederholt, und die Cannabisindustrie war bis dato eine typische Geschichte von Aufschwung und Niedergang.<\/p>\n<h3><strong>Augenmerk<\/strong><\/h3>\n<p>Da sich die Cannabism\u00e4rkte jedoch bereinigt haben, sollten Investoren beginnen, sich nach Unternehmen umzusehen, die sich l\u00e4ngerfristig positioniert haben, \u00fcber die wichtigsten Grundlagen verf\u00fcgen und ihr Augenmerk auf ein bestimmtes Segment der medizinischen Cannabis-Lieferkette richten.<\/p>\n<p>Erfreulicherweise befindet sich Bedrocan in einer einzigartigen Position, wenn man unsere Beziehung zum OMC, unsere Rolle als Vertragshersteller und die Tatsache ber\u00fccksichtigt, dass wir nie externem Druck, wie den Kr\u00e4ften des Kapitalmarktes, ausgesetzt waren.<\/p>\n<p>Wir sind fokussiert auf das, was wir von der Pike auf beherrschen &#8211; den Anbau hochwertiger, standardisierter medizinischer Cannabisbl\u00fcten.<\/p>\n<p>Wie sich herausstellt, ist eines der gr\u00f6\u00dften Probleme, mit denen der medizinische Cannabismarkt derzeit auf der anbautechnischen Ebene konfrontiert ist, die Produktion von Cannabisbl\u00fcten, die h\u00f6chsten Qualit\u00e4tsstandards entsprechen und letztendlich die erforderliche Konsistenz von Charge zu Charge in Bezug auf den Cannabinoidgehalt erreichen, um effektiv als Heilmittel eingesetzt werden zu k\u00f6nnen.<\/p>\n<h3><strong>Spezialisierung<\/strong><\/h3>\n<p>Wir sind der Meinung, dass die Spezialisierung ein Trend ist, der sich auf dem medizinischen Cannabismarkt weiter entwickeln wird.<\/p>\n<p>Angesichts der kapitalintensiven Natur medizinischer Cannabisherstellung im Allgemeinen ist die vollst\u00e4ndige vertikale Integration eine n\u00e4rrische Entscheidung, und es scheint uns sinnvoller, mit Unternehmen \u00fcber die gesamte Lieferkette hinweg zusammenzuarbeiten. Was \u00fcbrigens in jeder regul\u00e4ren Branche geschieht.<\/p>\n<p>Letztendlich hoffen wir, dass medizinisches Cannabis wie jedes andere medizinische Produkt behandelt wird und dass der normale pharmazeutische Weg beschritten wird. Dieser Weg ist definitiv zeit- und kostenintensiv, und auf der Suche nach gr\u00f6\u00dferen Ertr\u00e4gen haben Unternehmer begonnen, ihre Ressourcen weg vom medizinischen Cannabismarkt hin zum Konsummarkt zu verlagern, was nicht selten auf Kosten des medizinischen Cannabispatienten erfolgt.<\/p>\n<p>Die Auswirkungen des j\u00fcngsten Aufschwungs auf dem Cannabismarkt verst\u00e4rken diesen Trend nur noch weiter. Tats\u00e4chlich hat es nie eine Zeit von gr\u00f6\u00dferer Bedeutung gegeben, in ein verantwortungsbewusstes medizinisches Cannabis-\u00d6kosystem zu investieren.<\/p>\n<p>Wir bei Bedrocan werden weiterhin das tun, was wir seit unserer Gr\u00fcndung getan haben: Anbau im Dienste unserer Patienten.[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1590404292136{margin-bottom: 0px !important;}&#8221;]In den vergangenen Jahren gab es einen enormen Hype um die internationale Cannabisbranche. Dieser Hype, der haupts\u00e4chlich auf den boomenden kanadischen Cannabis Markt zur\u00fcckzuf\u00fchren ist, hat insbesondere bei Investoren in diesem Sektor unrealistische Erwartungen geweckt.\u00a0Angesichts der Tatsache, dass immer mehr Cannabis-Unternehmen nicht in der Lage sind, diesen \u00fcberh\u00f6hten Anspr\u00fcchen gerecht zu werden, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[140],"tags":[],"class_list":["post-34562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cannabis-Investitionen - Ein Hype oder eine ernsthafte Investition?<\/title>\n<meta name=\"description\" content=\"Welche regulatorischen Herausforderungen k\u00f6nnen auftreten in Cannabis-Investitionen? Hier finden Sie einige wichtige Informationen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cannabis-Investitionen - Ein Hype oder eine ernsthafte Investition?\" \/>\n<meta property=\"og:description\" content=\"Welche regulatorischen Herausforderungen k\u00f6nnen auftreten in Cannabis-Investitionen? Hier finden Sie einige wichtige Informationen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Bedrocan - standardised medicinal cannabis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bedrocan\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-06T09:39:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T15:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bedrocan.com\/wp-content\/uploads\/cannabis-leaf_lr-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Femke Starrenburg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Femke Starrenburg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/\"},\"author\":{\"name\":\"Femke Starrenburg\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/person\\\/0498aa6a37da27bb2d8043ccef680ecb\"},\"headline\":\"Aktueller Stand medizinischer Cannabis-Investitionen\",\"datePublished\":\"2020-05-06T09:39:19+00:00\",\"dateModified\":\"2026-06-22T15:10:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/\"},\"wordCount\":2435,\"publisher\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/cannabis-leaf_lr-8.jpg\",\"articleSection\":[\"Archive\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/\",\"name\":\"Cannabis-Investitionen - Ein Hype oder eine ernsthafte Investition?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/cannabis-leaf_lr-8.jpg\",\"datePublished\":\"2020-05-06T09:39:19+00:00\",\"dateModified\":\"2026-06-22T15:10:46+00:00\",\"description\":\"Welche regulatorischen Herausforderungen k\u00f6nnen auftreten in Cannabis-Investitionen? Hier finden Sie einige wichtige Informationen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/cannabis-leaf_lr-8.jpg\",\"contentUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/cannabis-leaf_lr-8.jpg\",\"width\":1350,\"height\":900,\"caption\":\"Cannabis-Investitionen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/aktueller-stand-medizinischer-cannabis-investitionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktueller Stand medizinischer Cannabis-Investitionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/\",\"name\":\"Bedrocan\",\"description\":\"medicinal cannabis\",\"publisher\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#organization\",\"name\":\"Bedrocan\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/logo-bedrocan-mail.png\",\"contentUrl\":\"https:\\\/\\\/bedrocan.com\\\/wp-content\\\/uploads\\\/logo-bedrocan-mail.png\",\"width\":185,\"height\":31,\"caption\":\"Bedrocan\"},\"image\":{\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Bedrocan\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bedrocan\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bedrocan_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bedrocan.com\\\/de\\\/#\\\/schema\\\/person\\\/0498aa6a37da27bb2d8043ccef680ecb\",\"name\":\"Femke Starrenburg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b80fc0034ccace316b8761c71cd06e86921c6bae82d77d746d056c317afda425?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b80fc0034ccace316b8761c71cd06e86921c6bae82d77d746d056c317afda425?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b80fc0034ccace316b8761c71cd06e86921c6bae82d77d746d056c317afda425?s=96&d=mm&r=g\",\"caption\":\"Femke Starrenburg\"},\"sameAs\":[\"http:\\\/\\\/bedrocan.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cannabis-Investitionen - Ein Hype oder eine ernsthafte Investition?","description":"Welche regulatorischen Herausforderungen k\u00f6nnen auftreten in Cannabis-Investitionen? Hier finden Sie einige wichtige Informationen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/","og_locale":"de_DE","og_type":"article","og_title":"Cannabis-Investitionen - Ein Hype oder eine ernsthafte Investition?","og_description":"Welche regulatorischen Herausforderungen k\u00f6nnen auftreten in Cannabis-Investitionen? Hier finden Sie einige wichtige Informationen.","og_url":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/","og_site_name":"Bedrocan - standardised medicinal cannabis","article_publisher":"https:\/\/www.facebook.com\/Bedrocan","article_published_time":"2020-05-06T09:39:19+00:00","article_modified_time":"2026-06-22T15:10:46+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/bedrocan.com\/wp-content\/uploads\/cannabis-leaf_lr-8.jpg","type":"image\/jpeg"}],"author":"Femke Starrenburg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Femke Starrenburg","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#article","isPartOf":{"@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/"},"author":{"name":"Femke Starrenburg","@id":"https:\/\/bedrocan.com\/de\/#\/schema\/person\/0498aa6a37da27bb2d8043ccef680ecb"},"headline":"Aktueller Stand medizinischer Cannabis-Investitionen","datePublished":"2020-05-06T09:39:19+00:00","dateModified":"2026-06-22T15:10:46+00:00","mainEntityOfPage":{"@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/"},"wordCount":2435,"publisher":{"@id":"https:\/\/bedrocan.com\/de\/#organization"},"image":{"@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#primaryimage"},"thumbnailUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/cannabis-leaf_lr-8.jpg","articleSection":["Archive"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/","url":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/","name":"Cannabis-Investitionen - Ein Hype oder eine ernsthafte Investition?","isPartOf":{"@id":"https:\/\/bedrocan.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#primaryimage"},"image":{"@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#primaryimage"},"thumbnailUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/cannabis-leaf_lr-8.jpg","datePublished":"2020-05-06T09:39:19+00:00","dateModified":"2026-06-22T15:10:46+00:00","description":"Welche regulatorischen Herausforderungen k\u00f6nnen auftreten in Cannabis-Investitionen? Hier finden Sie einige wichtige Informationen.","breadcrumb":{"@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#primaryimage","url":"https:\/\/bedrocan.com\/wp-content\/uploads\/cannabis-leaf_lr-8.jpg","contentUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/cannabis-leaf_lr-8.jpg","width":1350,"height":900,"caption":"Cannabis-Investitionen"},{"@type":"BreadcrumbList","@id":"https:\/\/bedrocan.com\/de\/aktueller-stand-medizinischer-cannabis-investitionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bedrocan.com\/de\/"},{"@type":"ListItem","position":2,"name":"Aktueller Stand medizinischer Cannabis-Investitionen"}]},{"@type":"WebSite","@id":"https:\/\/bedrocan.com\/de\/#website","url":"https:\/\/bedrocan.com\/de\/","name":"Bedrocan","description":"medicinal cannabis","publisher":{"@id":"https:\/\/bedrocan.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bedrocan.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bedrocan.com\/de\/#organization","name":"Bedrocan","url":"https:\/\/bedrocan.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bedrocan.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/bedrocan.com\/wp-content\/uploads\/logo-bedrocan-mail.png","contentUrl":"https:\/\/bedrocan.com\/wp-content\/uploads\/logo-bedrocan-mail.png","width":185,"height":31,"caption":"Bedrocan"},"image":{"@id":"https:\/\/bedrocan.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bedrocan","https:\/\/www.linkedin.com\/company\/bedrocan\/","https:\/\/www.instagram.com\/bedrocan_international\/"]},{"@type":"Person","@id":"https:\/\/bedrocan.com\/de\/#\/schema\/person\/0498aa6a37da27bb2d8043ccef680ecb","name":"Femke Starrenburg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b80fc0034ccace316b8761c71cd06e86921c6bae82d77d746d056c317afda425?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b80fc0034ccace316b8761c71cd06e86921c6bae82d77d746d056c317afda425?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b80fc0034ccace316b8761c71cd06e86921c6bae82d77d746d056c317afda425?s=96&d=mm&r=g","caption":"Femke Starrenburg"},"sameAs":["http:\/\/bedrocan.com"]}]}},"_links":{"self":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts\/34562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/comments?post=34562"}],"version-history":[{"count":8,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts\/34562\/revisions"}],"predecessor-version":[{"id":261321,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/posts\/34562\/revisions\/261321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/media\/34229"}],"wp:attachment":[{"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/media?parent=34562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/categories?post=34562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bedrocan.com\/de\/wp-json\/wp\/v2\/tags?post=34562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}